{"id":16446,"date":"2020-11-02T18:09:50","date_gmt":"2020-11-02T18:09:50","guid":{"rendered":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/rotgla-i-corbera\/"},"modified":"2021-02-24T17:08:50","modified_gmt":"2021-02-24T17:08:50","slug":"rotgla-i-corbera","status":"publish","type":"page","link":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/","title":{"rendered":"Rotgl\u00e0 i Corber\u00e0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16446\" class=\"elementor elementor-16446 elementor-8086\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcc35bc elementor-section-full_width elementor-hidden-tablet elementor-hidden-phone elementor-section-height-default elementor-section-height-default\" data-id=\"fcc35bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;bc8c9db&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0badc18\" data-id=\"0badc18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e2deef elementor-widget elementor-widget-raven-image\" data-id=\"8e2deef\" data-element_type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" src=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/elementor\/thumbs\/Rotgla-01-pjkpk3f7yp1o8aavs5ommj447ylsw58oviefwnami8.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-236a486 elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"236a486\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;51bee02&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad6f8ea\" data-id=\"ad6f8ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6762da2 elementor-widget elementor-widget-raven-image\" data-id=\"6762da2\" data-element_type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" src=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/elementor\/thumbs\/Rotgla-01-pjkpk3f7yp3y2no14gegqyg5rcelzp5f9gds0heiog.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bbae8a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bbae8a\" data-element_type=\"section\" id=\"pobles\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;69e5e79&quot;,&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce89ef7\" data-id=\"ce89ef7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-029f389 elementor-widget elementor-widget-heading\" data-id=\"029f389\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?page_id=16361\">PUEBLOS CON ENCANTO<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86ee19a elementor-widget elementor-widget-heading\" data-id=\"86ee19a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rotgl\u00e0 i Corber\u00e0<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e05e7a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9e05e7a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ed595 elementor-widget elementor-widget-text-editor\" data-id=\"b2ed595\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Rotgl\u00e0 i Corber\u00e0<\/strong> es un municipio de la comarca de la Costera que limita con las localidades de Llanera de Ranes, la Granja de la Costera y la Llosa de Ranes. Originariamente fueron dos alquer\u00edas musulmanas independientes, que despu\u00e9s de la conquista pasaron a manos de caballeros y ciudadanos de X\u00e0tiva. Hay que decir que en 1520 sufrieron un saqueo a manos de los <em>agermanats de X\u00e0tiva<\/em>. En 1854 los dos n\u00facleos urbanos se fusionaron en un solo municipio.<\/p><p>Como en otros pueblos de la Costera, este lugar ha estado habitado desde antiguo. A su alrededor se han encontrado varios yacimientos arqueol\u00f3gicos: en el yacimiento de Carraposa, de \u00e9poca prerromana, se encontraron ajuares funerarios y cer\u00e1micas \u00edberas; en el de la Coroneta, cer\u00e1micas \u00edberas y \u00e1nforas fenicio-p\u00fanicos; y en el yacimiento del Gars, se descubrieron las ruinas de una villa romana.<\/p><p>En esta localidad son numerosos los acu\u00edferos y filtraciones que dan lugar a las numerosas fuentes del municipio: la fuente de la Porta, la de Fidel, la del Canari y la fuente de Canya.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-860009c elementor-widget elementor-widget-jet-video\" data-id=\"860009c\" data-element_type=\"widget\" id=\"video\" data-widget_type=\"jet-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-video jet-elements\">\n<div class=\"jet-video jet-video--fa5-compat jet-video-aspect-ratio jet-video-aspect-ratio--16-9\" data-settings=\"{&quot;lightbox&quot;:false,&quot;autoplay&quot;:false}\"><iframe class=\"jet-video-iframe\" allowfullscreen title=\"Reproductor de v\u00eddeo youtube\" data-lazy-load=\"https:\/\/www.youtube.com\/embed\/wCVZA6u3-VY?feature=oembed&amp;start&amp;end&amp;wmode=opaque&amp;autoplay=0&amp;loop=0&amp;controls=1&amp;mute=0&amp;rel=0&amp;modestbranding=0\" allow=\"autoplay;encrypted-media\"><\/iframe>\n<div class=\"jet-video__overlay jet-video__overlay--custom-bg\" style=\"background-image: url(https:\/\/i.ytimg.com\/vi_webp\/wCVZA6u3-VY\/maxresdefault.webp);\">\n<div class=\"jet-video__play-button jet-video__play-button--animation-pulse\" role=\"button\" tabindex=\"0\" aria-label=\"Video play button\"><span class=\"jet-elements-icon jet-video__play-button-icon\"><i aria-hidden=\"true\" class=\"far fa-play-circle\"><\/i><\/span>\t<span class=\"elementor-screen-only\">Play Video<\/span>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aa7ca3 elementor-widget elementor-widget-text-editor\" data-id=\"9aa7ca3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Dentro del pueblo hay que destacar el antiguo secador de tabaco, edificio que se ha recuperado y restaurado poniendo en valor sus naves, a las cuales se les ha concedido una funci\u00f3n social, cultural y de servicio a los vecinos. Una parte del edificio es la actual sede del Ayuntamiento. Dentro se encuentra el <strong>Museo del Tabaco<\/strong>, donde podemos conocer la historia del municipio a trav\u00e9s de una actividad tradicional como fue la elaboraci\u00f3n de tabaco.<\/p>\n<p>La iglesia principal de Rotgl\u00e0 i Corber\u00e0 es la de <strong>San Juan Bautista<\/strong>. En la misma plaza estaba ubicado el antiguo palacio se\u00f1orial de los Rotgl\u00e0, del cual todav\u00eda se conservan indicios de su existencia en una de las casas. Otro edificio con inter\u00e9s es la antigua <em><strong>Venta del Rey<\/strong><\/em>, de la cual se conserva \u00fanicamente la fachada con los arcos de las ventanas y puertas, as\u00ed como una inscripci\u00f3n que data de la mitad del siglo XVIII. Dentro del casco urbano se encuentra <strong>la ermita de la Virgen del Socorro<\/strong> (conocida popularmente como <em>La Capilla de la Socorreta<\/em>). Hay que destacar uno de los edificios m\u00e1s antiguos de la comarca de la Costera, la llamada <strong>Torre Blanca<\/strong>, una fortaleza medieval encalada que actualmente se encuentra restaurada.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23995fa elementor-widget elementor-widget-gallery\" data-id=\"23995fa\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:5,&quot;columns_tablet&quot;:5,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:16,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;1:1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_mobile&quot;:1,&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-05.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODA5NSwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvUm90Z2xhLTA1LmpwZyIsInNsaWRlc2hvdyI6IjIzOTk1ZmEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-05-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-09.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODA5OSwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvUm90Z2xhLTA5LmpwZyIsInNsaWRlc2hvdyI6IjIzOTk1ZmEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-09-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-04.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODA5NCwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvUm90Z2xhLTA0LmpwZyIsInNsaWRlc2hvdyI6IjIzOTk1ZmEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-04-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-08.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODA5OCwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvUm90Z2xhLTA4LmpwZyIsInNsaWRlc2hvdyI6IjIzOTk1ZmEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-08-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/alcudia-crespins-03.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODA5MCwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvYWxjdWRpYS1jcmVzcGlucy0wMy5qcGciLCJzbGlkZXNob3ciOiIyMzk5NWZhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/alcudia-crespins-03-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-10.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODEwMCwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvUm90Z2xhLTEwLmpwZyIsInNsaWRlc2hvdyI6IjIzOTk1ZmEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-10-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-06.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODA5NiwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvUm90Z2xhLTA2LmpwZyIsInNsaWRlc2hvdyI6IjIzOTk1ZmEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-06-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-07.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23995fa\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODA5NywidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMVwvUm90Z2xhLTA3LmpwZyIsInNsaWRlc2hvdyI6IjIzOTk1ZmEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/Rotgla-07-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PUEBLOS CON ENCANTO Rotgl\u00e0 i Corber\u00e0 Rotgl\u00e0 i Corber\u00e0 es un municipio de la comarca de la Costera que limita con las localidades de Llanera de Ranes, la Granja de la Costera y la Llosa de Ranes. Originariamente fueron dos alquer\u00edas musulmanas independientes, que despu\u00e9s de la conquista pasaron a manos de caballeros y ciudadanos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15076,"parent":16361,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rotgl\u00e0 i Corber\u00e0 - Turisme La Costera<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Rotgl\u00e0 i Corber\u00e0 y sus principales recursos tur\u00edsticos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rotgl\u00e0 i Corber\u00e0 - Turisme La Costera\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Rotgl\u00e0 i Corber\u00e0 y sus principales recursos tur\u00edsticos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/\" \/>\n<meta property=\"og:site_name\" content=\"Turisme la Costera l Tesoros del interior\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T17:08:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/alcudia-crespins-03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/\",\"url\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/\",\"name\":\"Rotgl\u00e0 i Corber\u00e0 - Turisme La Costera\",\"isPartOf\":{\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website\"},\"datePublished\":\"2020-11-02T18:09:50+00:00\",\"dateModified\":\"2021-02-24T17:08:50+00:00\",\"description\":\"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Rotgl\u00e0 i Corber\u00e0 y sus principales recursos tur\u00edsticos.\",\"breadcrumb\":{\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pueblos con encanto\",\"item\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pobles-amb-encant\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rotgl\u00e0 i Corber\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website\",\"url\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/\",\"name\":\"Turisme la Costera l Tesoros del interior\",\"description\":\"Descobreix els tresors que amaga l&#039;interior de Val\u00e8ncia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rotgl\u00e0 i Corber\u00e0 - Turisme La Costera","description":"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Rotgl\u00e0 i Corber\u00e0 y sus principales recursos tur\u00edsticos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/","og_locale":"es_ES","og_type":"article","og_title":"Rotgl\u00e0 i Corber\u00e0 - Turisme La Costera","og_description":"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Rotgl\u00e0 i Corber\u00e0 y sus principales recursos tur\u00edsticos.","og_url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/","og_site_name":"Turisme la Costera l Tesoros del interior","article_modified_time":"2021-02-24T17:08:50+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/11\/alcudia-crespins-03.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/","url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/","name":"Rotgl\u00e0 i Corber\u00e0 - Turisme La Costera","isPartOf":{"@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website"},"datePublished":"2020-11-02T18:09:50+00:00","dateModified":"2021-02-24T17:08:50+00:00","description":"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Rotgl\u00e0 i Corber\u00e0 y sus principales recursos tur\u00edsticos.","breadcrumb":{"@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/rotgla-i-corbera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/"},{"@type":"ListItem","position":2,"name":"Pueblos con encanto","item":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pobles-amb-encant\/"},{"@type":"ListItem","position":3,"name":"Rotgl\u00e0 i Corber\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website","url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/","name":"Turisme la Costera l Tesoros del interior","description":"Descobreix els tresors que amaga l&#039;interior de Val\u00e8ncia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages\/16446"}],"collection":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/comments?post=16446"}],"version-history":[{"count":0,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages\/16446\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages\/16361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/media\/15076"}],"wp:attachment":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/media?parent=16446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}