{"id":16363,"date":"2020-10-31T12:51:40","date_gmt":"2020-10-31T12:51:40","guid":{"rendered":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/barxeta\/"},"modified":"2021-02-24T10:37:50","modified_gmt":"2021-02-24T10:37:50","slug":"barxeta","status":"publish","type":"page","link":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/","title":{"rendered":"Barxeta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16363\" class=\"elementor elementor-16363 elementor-7766\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcc35bc elementor-section-full_width elementor-hidden-tablet elementor-hidden-phone elementor-section-height-default elementor-section-height-default\" data-id=\"fcc35bc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;31b089e&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0badc18\" data-id=\"0badc18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e2deef elementor-widget elementor-widget-raven-image\" data-id=\"8e2deef\" data-element_type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" src=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/elementor\/thumbs\/Barxeta-02-oxq71judc9btld63idoxv0vkxxohj5ed1cbjrizp0w.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-236a486 elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"236a486\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;9f9beea&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad6f8ea\" data-id=\"ad6f8ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6762da2 elementor-widget elementor-widget-raven-image\" data-id=\"6762da2\" data-element_type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" src=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/elementor\/thumbs\/Barxeta-02-oxq71judc9e3fqj8uoerzg7mhbhampb3faavvd3l74.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bbae8a elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bbae8a\" data-element_type=\"section\" id=\"pobles\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;69e5e79&quot;,&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce89ef7\" data-id=\"ce89ef7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3462cf9 elementor-widget elementor-widget-heading\" data-id=\"3462cf9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?page_id=16361\">PUEBLOS CON ENCANTO<\/a><\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86ee19a elementor-widget elementor-widget-heading\" data-id=\"86ee19a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Barxeta<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e05e7a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9e05e7a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ed595 elementor-widget elementor-widget-text-editor\" data-id=\"b2ed595\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Barxeta<\/strong> se encuentra en el extremo m\u00e1s oriental de la Costera. Su nombre tiene or\u00edgenes isl\u00e1micos, fue una alquer\u00eda musulmana conquistada por <strong>Jaume I<\/strong>. En 1488 era propiedad de los se\u00f1ores de Tallada, de ascendencia italiana, y en 1574 consigui\u00f3 la independencia de X\u00e0tiva. El valle de Barxeta siempre ha sido habitado y son diversos los yacimientos arqueol\u00f3gicos existentes en el t\u00e9rmino, destacando <strong>Casa Perot<\/strong>, donde se encontraron restos de un poblado \u00edbero-romano, y <strong>Els Terrers<\/strong> y <strong>La Judia<\/strong>, donde se descubri\u00f3 un poblado amurallado de la edad del bronce.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deba49d elementor-widget elementor-widget-image\" data-id=\"deba49d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-03.jpg\" class=\"attachment-full size-full wp-image-14912\" alt=\"\" srcset=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-03.jpg 1920w, https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-03-300x169.jpg 300w, https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-03-1024x576.jpg 1024w, https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-03-768x432.jpg 768w, https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-03-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faaa3aa elementor-widget elementor-widget-text-editor\" data-id=\"faaa3aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El r\u00edo Barxeta recorre el valle de levante a poniente con un caudal de agua permanente y limpio que atrae la vida salvaje. <strong><a href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?page_id=16286\">El Paraje natural del r\u00edo de Barxeta<\/a><\/strong> fue declarado paraje natural municipal en 2008. Son numerosas las especies de fauna que se encuentran en el r\u00edo, un lugar id\u00f3neo para desarrollar su actividad vital. Siguiendo el margen del r\u00edo se encuentran varias construcciones para aprovechar sus aguas en el regad\u00edo, como acueductos y acequias.<\/p>\n<p>Los amantes del senderismo tambi\u00e9n encontrar\u00e1n en Barxeta rutas muy interesantes, como <strong><a href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?page_id=16507\">la ruta de la Barsella<\/a><\/strong> o <strong><a href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?page_id=16541\">la ruta de la Sierra de la Corsa y Requena<\/a><\/strong>, compuesta de bellos y espectaculares paisajes. Abundan en estas monta\u00f1as las canteras de m\u00e1rmol y granito y es muy apreciado desde la antig\u00fcedad el m\u00e1rmol rosa del <strong>Buixcarr\u00f3<\/strong>.<\/p>\n<p>En el pueblo se producen quesos artesanales de gran calidad. Los <strong>quesos de Barxeta<\/strong> recogen la tradici\u00f3n de varias generaciones dedicadas a la ganader\u00eda de ovejas y a la elaboraci\u00f3n artesanal de quesos. Un producto que se comercializa directamente en los mercados de proximidad y llega al consumidor sin ninguna clase de conservantes. Son quesos receptores de premios nacionales e internacionales.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ae498a elementor-widget elementor-widget-gallery\" data-id=\"2ae498a\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:5,&quot;columns_tablet&quot;:5,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:25,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:16,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;1:1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_mobile&quot;:1,&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-09.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ae498a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3NSwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMFwvQmFyeGV0YS0wOS5qcGciLCJzbGlkZXNob3ciOiIyYWU0OThhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-09-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-10.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ae498a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3NiwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMFwvQmFyeGV0YS0xMC5qcGciLCJzbGlkZXNob3ciOiIyYWU0OThhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-10-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-08.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ae498a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3NCwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMFwvQmFyeGV0YS0wOC5qcGciLCJzbGlkZXNob3ciOiIyYWU0OThhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-08-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-07.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ae498a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3MywidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMFwvQmFyeGV0YS0wNy5qcGciLCJzbGlkZXNob3ciOiIyYWU0OThhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-07-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-04.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ae498a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3MCwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMFwvQmFyeGV0YS0wNC5qcGciLCJzbGlkZXNob3ciOiIyYWU0OThhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-04-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-05.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ae498a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3MSwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMFwvQmFyeGV0YS0wNS5qcGciLCJzbGlkZXNob3ciOiIyYWU0OThhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-05-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-06.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2ae498a\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3MiwidXJsIjoiaHR0cHM6XC9cL3VucnVmZmxlZC1yb3NhbGluZC4xODUtMTI5LTI0OS02My5wbGVzay5wYWdlXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIwXC8xMFwvQmFyeGV0YS0wNi5qcGciLCJzbGlkZXNob3ciOiIyYWU0OThhIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-06-500x500.jpg\" data-width=\"500\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PUEBLOS CON ENCANTO Barxeta Barxeta se encuentra en el extremo m\u00e1s oriental de la Costera. Su nombre tiene or\u00edgenes isl\u00e1micos, fue una alquer\u00eda musulmana conquistada por Jaume I. En 1488 era propiedad de los se\u00f1ores de Tallada, de ascendencia italiana, y en 1574 consigui\u00f3 la independencia de X\u00e0tiva. El valle de Barxeta siempre ha sido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14918,"parent":16361,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Barxeta - Turisme La Costera<\/title>\n<meta name=\"description\" content=\"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Barxeta y sus principales recursos tur\u00edsticos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barxeta - Turisme La Costera\" \/>\n<meta property=\"og:description\" content=\"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Barxeta y sus principales recursos tur\u00edsticos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/\" \/>\n<meta property=\"og:site_name\" content=\"Turisme la Costera l Tesoros del interior\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T10:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-09.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/\",\"url\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/\",\"name\":\"Barxeta - Turisme La Costera\",\"isPartOf\":{\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website\"},\"datePublished\":\"2020-10-31T12:51:40+00:00\",\"dateModified\":\"2021-02-24T10:37:50+00:00\",\"description\":\"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Barxeta y sus principales recursos tur\u00edsticos.\",\"breadcrumb\":{\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pueblos con encanto\",\"item\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pobles-amb-encant\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barxeta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website\",\"url\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/\",\"name\":\"Turisme la Costera l Tesoros del interior\",\"description\":\"Descobreix els tresors que amaga l&#039;interior de Val\u00e8ncia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barxeta - Turisme La Costera","description":"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Barxeta y sus principales recursos tur\u00edsticos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/","og_locale":"es_ES","og_type":"article","og_title":"Barxeta - Turisme La Costera","og_description":"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Barxeta y sus principales recursos tur\u00edsticos.","og_url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/","og_site_name":"Turisme la Costera l Tesoros del interior","article_modified_time":"2021-02-24T10:37:50+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/wp-content\/uploads\/2020\/10\/Barxeta-09.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/","url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/","name":"Barxeta - Turisme La Costera","isPartOf":{"@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website"},"datePublished":"2020-10-31T12:51:40+00:00","dateModified":"2021-02-24T10:37:50+00:00","description":"En esta p\u00e1gina, encontrar\u00e1s informaci\u00f3n relevante sobre el t\u00e9rmino de Barxeta y sus principales recursos tur\u00edsticos.","breadcrumb":{"@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pueblos-con-encanto\/barxeta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/"},{"@type":"ListItem","position":2,"name":"Pueblos con encanto","item":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/pobles-amb-encant\/"},{"@type":"ListItem","position":3,"name":"Barxeta"}]},{"@type":"WebSite","@id":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/#website","url":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/","name":"Turisme la Costera l Tesoros del interior","description":"Descobreix els tresors que amaga l&#039;interior de Val\u00e8ncia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages\/16363"}],"collection":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/comments?post=16363"}],"version-history":[{"count":0,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages\/16363\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/pages\/16361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/media\/14918"}],"wp:attachment":[{"href":"https:\/\/unruffled-rosalind.185-129-249-63.plesk.page\/es\/wp-json\/wp\/v2\/media?parent=16363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}